{"id":39832,"date":"2020-11-23T11:07:36","date_gmt":"2020-11-23T10:07:36","guid":{"rendered":"https:\/\/packaging-journal.de\/?p=39832"},"modified":"2020-11-23T11:07:36","modified_gmt":"2020-11-23T10:07:36","slug":"black-recycled-paper-ecoblack-for-fine-packaging","status":"publish","type":"post","link":"https:\/\/packaging-journal.de\/en\/schwarzes-recyclingpapier-ecoblack-fuer-edle-verpackungen\/","title":{"rendered":"Wrap black in paper with EcoBlack"},"content":{"rendered":"<div class=\"packa-d-billboard packa-entity-placement\" style=\"text-align: center;\" id=\"packa-1808285661\"><div id=\"packa-2303438225\"><a data-no-instant=\"1\" href=\"https:\/\/wemakepackaging.it\/en\/home\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"1777969430042_banner_ASK_TRUST_PACK_840x210\"><!--noptimize--><img src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210.jpg\" alt=\"\"  srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210.jpg 1750w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-300x75.jpg 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1024x256.jpg 1024w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-768x192.jpg 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1536x384.jpg 1536w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-18x5.jpg 18w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-332x83.jpg 332w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-664x166.jpg 664w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-688x172.jpg 688w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1044x261.jpg 1044w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1400x350.jpg 1400w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1320x330.jpg 1320w\" sizes=\"(max-width: 1750px) 100vw, 1750px\" width=\"840\" height=\"210\"  style=\" max-width: 100%; height: auto;\" \/><!--\/noptimize--><\/a><\/div><\/div><p>Koehler Greiz bringt jetzt mit EcoBlack ein schwarzes Recyclingpapier auf den Markt, das sich besonders f\u00fcr die Veredelung mit Pr\u00e4gefolien eignet und vermehrt auch in der Verpackung zum Einsatz kommt.<\/p>\n<p>Recyclingpapiere aus 100 Prozent Sekund\u00e4rfaserstoffen haben die Koehler Paper Group in den vergangenen Jahren zum Premiumanbieter f\u00fcr Kreativkarton f\u00fcr den Bastel- und B\u00fcrobereich gemacht. Jetzt finden die Papiere ihren <strong>Weg auch in die Verpackungsindustrie<\/strong> und dort sogar in die High-End-Segmente. Das Werk am th\u00fcringischen Standort der <a href=\"https:\/\/packaging-journal.de\/tag\/koehler-paper-group\/\">Koehler Paper Group<\/a> hat sein Papier-Portfolio jetzt mit dem j\u00fcngsten Produkt <strong>EcoBlack<\/strong> erg\u00e4nzt.<\/p>\n<blockquote><p>\u201eEcoBlack ist ein edles Papier, das durch ein tiefes, sattes Schwarz besticht. Wir haben es speziell f\u00fcr den Bereich der edlen Verpackungen entwickelt. Es reiht sich als logische Konsequenz in das Sortiment unserer farbintensiven Recyclingpapiere ein. Wir bedienen hiermit den Wunsch unserer Kunden nach Unbedenklichkeit f\u00fcr Gesundheit und Umwelt, der \u00c4sthetik nicht ausschlie\u00dfen muss. EcoBlack ist lichtecht, resistent gegen Ausbluten, Farbmigration und Abrieb\u201c. <strong>Udo Hollbach<\/strong>, Gesch\u00e4ftsf\u00fchrer der Koehler Greiz GmbH &amp; Co. KG<\/p><\/blockquote>\n<p>Da EcoBlack carbonfrei hergestellt wird, eignet es sich besonders f\u00fcr die Veredelung mit Pr\u00e4gefolien. Ob als Kreativkarton oder f\u00fcr den Einsatz im Verpackungsbereich: \u201eWir lassen uns auf das Storytelling unserer Kunden ein. Mit unseren Recyclingpapieren <em>Made in Germany<\/em> tragen wir mit einer runden Geschichte zum Kapitel Verpackung bei\u201c, erl\u00e4utert Udo Hollbach. Die <strong>Papiere bestehen aus recyceltem Material und k\u00f6nnen auch wieder in den Recyclingprozess \u00fcberf\u00fchrt<\/strong> werden \u2013 der vom Endkunden favorisierte geschlossene Kreislauf f\u00fcr Papier existiert verl\u00e4sslich. Die Papiere sind chlor- und s\u00e4urefrei und halten die strengen Richtlinien des Umweltzeichens <em>Blauer Engel<\/em> ein.<\/p><div class=\"packa-in-post-alle packa-entity-placement\" style=\"text-align: center;\" id=\"packa-4012206099\"><div id=\"packa-249892974\"><a data-no-instant=\"1\" href=\"https:\/\/packaging-journal.de\/en\/newsletter\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"PJ Eigenwerbung English 03\"><!--noptimize--><img src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03.png\" alt=\"\"  srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03.png 840w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-300x75.png 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-768x192.png 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-18x5.png 18w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-332x83.png 332w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-664x166.png 664w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-688x172.png 688w\" sizes=\"(max-width: 840px) 100vw, 840px\" width=\"840\" height=\"210\"  style=\" max-width: 100%; height: auto;\" \/><!--\/noptimize--><\/a><\/div><\/div>\n<h2>EcoBlack bietet gute Veredelungsm\u00f6glichkeiten<\/h2>\n<p>Insgesamt sieht Udo Hollbach <strong>f\u00fcr die Recyclingpapiere aus Greiz einen stark wachsenden Markt<\/strong>: \u201eDas Bed\u00fcrfnis nach nachhaltigen Verpackungen ist der beste Wegbereiter f\u00fcr unsere Recyclingpapiere. Ihre brillanten Farben, unser gro\u00dfes Sortiment, die konstant hohe Qualit\u00e4t unserer Produktion sowie die hohe Steifigkeit unserer Papiere bieten hervorragende Veredelungsm\u00f6glichkeiten, die die Produkteigenschaften der zu verpackenden G\u00fcter bereits in ihrer Verpackung sichtbar werden lassen. Und wir sind so flexibel, dass wir ab einer bestimmten Menge auch Papiere produzieren k\u00f6nnen, die<strong> individuell auf unsere Kunden zugeschnitten<\/strong> sind\u201c.<\/p>\n[infotext icon]Die Koehler Paper Group ist ein international agierender Hersteller von Spezialpapier. Das familiengef\u00fchrte Unternehmen aus Oberkirch, S\u00fcdwestdeutschland, produziert j\u00e4hrlich \u00fcber 500.000 Tonnen Papier, Karton und Holzschliffpappe an vier Standorten in Deutschland. Zu den Produkten z\u00e4hlen Thermopapier, Selbstdurchschreibepapier, Dekorpapier, Feinpapier, Recyclingpapier, Holzschliffpappe, Sublimationspapier und flexibles Verpackungspapier.[\/infotext]\n<p>Quelle: Koehler Paper Group<\/p><div id=\"packa-4257947248\" class=\"packa-inhalt packa-entity-placement\"><!--noptimize--><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-2686439340972671\" crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\" style=\"display:block;text-align:center\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-2686439340972671\" data-ad-slot=\"6171251825\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><!--\/noptimize--><\/div>\n","protected":false},"excerpt":{"rendered":"Koehler Greiz is now launching EcoBlack, a black recycled paper that is particularly suitable for finishing with embossing foils and is also increasingly being used in packaging.\u00a0","protected":false},"author":20,"featured_media":39834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"__cvm_playback_settings":[],"__cvm_video_id":"","rank_math_description":"","rank_math_focus_keyword":"","rank_math_title":"","csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22],"tags":[43,58826,31,32,1487,51],"class_list":{"0":"post-39832","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-packmittel-und-packstoffe","8":"tag-aus-den-unternehmen","9":"tag-koehler-paper-group","10":"tag-nachhaltigkeit-und-green-packaging","11":"tag-packmittel-und-packstoffe","12":"tag-papier-pappe-karton","13":"tag-verpackungsdruck-und-veredelung","14":"cs-entry","15":"cs-video-wrap"},"acf":[],"vimeo_video":null,"_links":{"self":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/posts\/39832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/comments?post=39832"}],"version-history":[{"count":0,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/posts\/39832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/media\/39834"}],"wp:attachment":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/media?parent=39832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/categories?post=39832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/tags?post=39832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}