{"id":41826,"date":"2021-02-06T08:37:37","date_gmt":"2021-02-06T07:37:37","guid":{"rendered":"https:\/\/packaging-journal.de\/?p=41826"},"modified":"2021-02-05T20:39:32","modified_gmt":"2021-02-05T19:39:32","slug":"schott-pharmaglas-corona-vaccine","status":"publish","type":"post","link":"https:\/\/packaging-journal.de\/en\/schott-pharmaglas-corona-impfstoff\/","title":{"rendered":"Pharma glass from Schott protects corona vaccine"},"content":{"rendered":"<div class=\"packa-d-billboard packa-entity-placement\" style=\"text-align: center;\" id=\"packa-3938907200\"><div id=\"packa-2753876742\"><a data-no-instant=\"1\" href=\"https:\/\/wemakepackaging.it\/en\/home\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"1777969430042_banner_ASK_TRUST_PACK_840x210\"><!--noptimize--><img src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210.jpg\" alt=\"\"  srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210.jpg 1750w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-300x75.jpg 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1024x256.jpg 1024w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-768x192.jpg 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1536x384.jpg 1536w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-18x5.jpg 18w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-332x83.jpg 332w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-664x166.jpg 664w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-688x172.jpg 688w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1044x261.jpg 1044w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1400x350.jpg 1400w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/05\/1777969430042_banner_ASK_TRUST_PACK_840x210-1320x330.jpg 1320w\" sizes=\"(max-width: 1750px) 100vw, 1750px\" width=\"840\" height=\"210\"  style=\" max-width: 100%; height: auto;\" \/><!--\/noptimize--><\/a><\/div><\/div><p>Noch nie wurde in so kurzer Zeit ein Impfstoff entwickelt, getestet und bereitgestellt. Nicht einmal ein Jahr hat es bis zu den ersten Corona-Impfungen gedauert. Dahinter steckt nicht nur eine wissenschaftliche, sondern auch eine logistische Leistung. Denn: Das Vakzin muss in gro\u00dfen Mengen produziert und abgef\u00fcllt, verpackt, transportiert und weltweit verteilt werden.<\/p>\n<p>Ein Gro\u00dfteil der Prim\u00e4rverpackung f\u00fcr den Impfstoff liefert der Mainzer Spezialglashersteller Schott. Seine Pharma-Fl\u00e4schchen kommen in drei Viertel der weltweiten COVID-19-Impfstoffprojekte zum Einsatz. Das <strong>hochreine, sogenannte Borosilicatglas<\/strong> hat Firmengr\u00fcnder Otto Schott 1887 in Jena entwickelt. Das Material ist hochgradig inert und sch\u00fctzt vor jeglichen Wechselwirkungen zwischen Medikament und Beh\u00e4lter, was es ideal f\u00fcr COVID-19-Impfstoffe macht.<\/p>\n<figure id=\"attachment_41829\" aria-describedby=\"caption-attachment-41829\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-41829 size-large\" src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-1024x576.jpg\" alt=\"Impfstofffl\u00e4schen aus Glas\" width=\"1024\" height=\"576\" srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-1024x576.jpg 1024w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-300x169.jpg 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-768x432.jpg 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-1536x864.jpg 1536w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-813x457.jpg 813w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-180x101.jpg 180w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-260x146.jpg 260w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-373x210.jpg 373w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-120x67.jpg 120w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-1320x743.jpg 1320w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19-600x338.jpg 600w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-covid19.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-41829\" class=\"wp-caption-text\">Schott wird Glasfl\u00e4schchen f\u00fcr rund zwei Milliarden Impfdosen liefern. (Bild: Schott AG)<\/figcaption><\/figure>\n<p>Schon vor Corona ist die Nachfrage nach Pharmaglas und -verpackungen stetig gestiegen. Bereits im M\u00e4rz 2019 verk\u00fcndeten die Mainzer daher <strong>das gr\u00f6\u00dfte Investitionsprogramm in der Unternehmensgeschichte<\/strong> \u2013 eine Milliarde US-Dollar im Pharmabereich.<\/p><div class=\"packa-in-post-alle packa-entity-placement\" style=\"text-align: center;\" id=\"packa-2480367891\"><div id=\"packa-479127962\"><a data-no-instant=\"1\" href=\"https:\/\/packaging-journal.de\/en\/newsletter\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"PJ Eigenwerbung English 03\"><!--noptimize--><img src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03.png\" alt=\"\"  srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03.png 840w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-300x75.png 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-768x192.png 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-18x5.png 18w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-332x83.png 332w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-664x166.png 664w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2026\/01\/PJ-Eigenwerbung-English-03-688x172.png 688w\" sizes=\"(max-width: 840px) 100vw, 840px\" width=\"840\" height=\"210\"  style=\" max-width: 100%; height: auto;\" \/><!--\/noptimize--><\/a><\/div><\/div>\n<blockquote>\n<figure id=\"attachment_41830\" aria-describedby=\"caption-attachment-41830\" style=\"width: 242px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"wp-image-41830 size-medium\" src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Fabian-Stoecker-242x300.jpg\" alt=\"Fabian St\u00f6cker Vice President Global Strategy and Innovation bei Schott Pharmaceutical Systems\" width=\"242\" height=\"300\" srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Fabian-Stoecker-242x300.jpg 242w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Fabian-Stoecker.jpg 336w\" sizes=\"(max-width: 242px) 100vw, 242px\" \/><figcaption id=\"caption-attachment-41830\" class=\"wp-caption-text\">(Bild: Schott AG)<\/figcaption><\/figure>\n<p>\u201e50 Prozent davon werden wir bis Ende 2021 bereits umgesetzt haben und sind dank des fr\u00fchzeitigen Invests in der Lage, die Kapazit\u00e4ten hochzufahren. Trotz der Corona-Krise sind alle Projekte weiter im Zeitplan.\u201c <strong>Fabian St\u00f6cker<\/strong>, Vice President Global Strategy and Innovation bei Schott Pharmaceutical Systems<\/p><\/blockquote>\n<h2><strong>Ausbau der Produktion von Glasr\u00f6hren<\/strong><\/h2>\n<p>Gerade hat der Glasspezialist verk\u00fcndet, in eine zweite Schmelzwanne f\u00fcr Pharmarohr in seinem Hauptwerk in Mainz zu investieren. Dort produziert Schott keine Fl\u00e4schchen oder Ampullen, daf\u00fcr aber <strong>die als Vorprodukt ben\u00f6tigen Glasrohre<\/strong>. Die neue Anlage soll Mitte 2022 in Betrieb gehen.<\/p>\n<blockquote><p>\u201eWir haben uns f\u00fcr den Standort Mainz entschieden, um unsere Produktionsbasis f\u00fcr Pharmaglasr\u00f6hren in Deutschland und Europa weiter zu st\u00e4rken. Dabei haben wir nat\u00fcrlich auch die hier ans\u00e4ssigen Hersteller von Impfstoffen gegen die COVID-19 Pandemie und die europ\u00e4ische Pharmaindustrie insgesamt im Blick.\u201c <strong>Dr. Frank Heinrich<\/strong>t, Vorstandsvorsitzender der Schott AG<\/p><\/blockquote>\n<p>Die Pharmaglasproduktion in Mainz geh\u00f6rt zu einem globalen Produktionsnetzwerk des Gesch\u00e4ftsbereichs Tubing, zu dem auch der Standort Mitterteich in der Oberpfalz sowie Fabriken in Brasilien, Indien und China geh\u00f6ren. Bereits im Herbst 2020 hat Schott seine<strong> Produktionskapazit\u00e4ten f\u00fcr Pharmarohr in Asien deutlich erweitert.<\/strong> Das Werk in Indien wurde um zwei neue Schmelzwannen zur Produktion von Pharmarohr ausgebaut und in <a href=\"https:\/\/packaging-journal.de\/?s=Spezialglashersteller+schott+\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">China<\/a> ein komplett neues Werk f\u00fcr Pharmarohr errichtet, das im November 2020 angetempert wurde.<\/p><div id=\"packa-3029307810\" class=\"packa-inhalt packa-entity-placement\"><!--noptimize--><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-2686439340972671\" crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\" style=\"display:block;text-align:center\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-2686439340972671\" data-ad-slot=\"6171251825\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><!--\/noptimize--><\/div>\n<p>Unter dem Markennamen FIOLAX produziert das Werk Borosilicat-Glasr\u00f6hren \u2013 das <strong>Basismaterial f\u00fcr pharmazeutische Verpackungen<\/strong> wie Fl\u00e4schchen, Ampullen, Spritzen und Karpulen, auf die die \u00fcberwiegende Mehrheit der COVID-19-Impfstoffprojekte angewiesen ist. Die Anlage mit einer Kapazit\u00e4t von zun\u00e4chst 20.000 Tonnen Glas pro Jahr ist mit modernster Produktionstechnologie ausgestattet und folgt der perfeXion-Philosophie \u2013 der <strong>100-Prozent-Kontrolle jeder einzelnen R\u00f6hre<\/strong> durch den Einsatz modernster Big-Data-Methoden.<\/p>\n<figure id=\"attachment_41833\" aria-describedby=\"caption-attachment-41833\" style=\"width: 873px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-41833 size-full\" src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Lebanon-PA-USA-Vial-Supply.png\" alt=\"Schott Werk in Lebanon USA\" width=\"873\" height=\"658\" srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Lebanon-PA-USA-Vial-Supply.png 873w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Lebanon-PA-USA-Vial-Supply-300x226.png 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Lebanon-PA-USA-Vial-Supply-768x579.png 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/Schott-Lebanon-PA-USA-Vial-Supply-600x452.png 600w\" sizes=\"(max-width: 873px) 100vw, 873px\" \/><figcaption id=\"caption-attachment-41833\" class=\"wp-caption-text\">Investition in den Ausbau der Produktion von Pharmabeh\u00e4ltern, u.a. am US-Standort in Lebanon. (Bild: Schott AG)<\/figcaption><\/figure>\n<p>Dies entspreche dem Ansatz der anderen Schott Pharmarohr-Produktionsst\u00e4tten weltweit. Die Produktion im neuen Werk komme zu einer Zeit, in der Borosilicatrohre sehr gefragt sind. Schott verkauft das Glas an externe Verpackungshersteller, verarbeitet die R\u00f6hren aber auch selbst zu Fl\u00e4schchen und anderen pharmazeutischen Beh\u00e4ltnissen. So investierte man auch auf der Converting-Seite <strong>weltweit in den Ausbau der Produktion von Pharmabeh\u00e4ltern<\/strong>, etwa mit neuen Linien im baden-w\u00fcrttembergischen M\u00fcllheim oder am US-Standort in Lebanon.<\/p>\n<h2><strong>Glasfl\u00e4schchen f\u00fcr zwei Milliarden Impfdosen<\/strong><\/h2>\n<p>Um den Impfstoff weltweit zu verteilen, sind Milliarden der kleinen Glasfl\u00e4schchen n\u00f6tig. \u201eIn Bezug auf COVID-19 haben wir uns dazu entschieden, <strong>nicht von St\u00fcckzahlen, sondern von Impfdosen<\/strong> zu sprechen. Hintergrund ist, dass die verschiedenen Projekte sehr unterschiedliche Konzepte verfolgen. Manche wollen eine Dosis in einem kleinen Fl\u00e4schchen verpacken, andere wiederum f\u00fcnf oder mehr Dosen in einem gr\u00f6\u00dferen Fl\u00e4schchen\u201c, so Fabian St\u00f6cker.<\/p>\n<p>\u201eStand heute haben wir <strong>Lieferabkommen mit \u00fcber 75 Prozent aller Impfstoffprojekte,<\/strong> die bereits zugelassen sind oder sich in klinischen Tests befinden. Wir d\u00fcrfen keine Details herausgeben, k\u00f6nnen aber sagen, dass es sich um weit vorangeschrittene Projekte handelt, \u00fcber die regelm\u00e4\u00dfig in den Medien berichtet wird. Z\u00e4hlt man das Volumen dieser Projekte zusammen, werden wir Fl\u00e4schchen f\u00fcr rund zwei Milliarden Impfdosen liefern.\u201c<\/p>\n<figure id=\"attachment_41834\" aria-describedby=\"caption-attachment-41834\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41834 size-large\" src=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-1024x675.jpg\" alt=\"Standardfl\u00e4schchen f\u00fcr Impfstoffe\" width=\"1024\" height=\"675\" srcset=\"https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-1024x675.jpg 1024w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-300x198.jpg 300w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-768x506.jpg 768w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-1536x1012.jpg 1536w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-1320x870.jpg 1320w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid-600x395.jpg 600w, https:\/\/packaging-journal.de\/wp-content\/uploads\/2021\/02\/schott-linie-covid.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-41834\" class=\"wp-caption-text\">ISO-genormte Standardfl\u00e4schchen stellt Schott t\u00e4glich millionenfach her. (Bild: Schott AG)<\/figcaption><\/figure>\n<p>Der Glashersteller ist optimistisch, dass der weltweite Bedarf gedeckt werden kann. Bereits vor der Pandemie h\u00e4tten alle gro\u00dfen Hersteller erhebliche Investitionen zur Kapazit\u00e4tserweiterung get\u00e4tigt, hei\u00dft es bei Schott. Zudem h\u00e4tten sich die Prozesse entlang der Lieferkette trotz Pandemie nicht ver\u00e4ndert. Sie beruhen auf standardisierten und etablierten Abl\u00e4ufen, bei denen die Medikamentenverpackung von Anfang an mitgeplant wird.<\/p>\n<p>St\u00f6cker: \u201eWir als Verpackungshersteller wissen mit mehreren Monaten Vorlauf, wann wir wie viele Fl\u00e4schchen liefern m\u00fcssen. Au\u00dferdem handelt es sich bei den zu liefernden Fl\u00e4schchen um ISO-genormte Standardfl\u00e4schchen. Diese stellen wir tagein, tagaus millionenfach her.\u201c Insgesamt liege die <strong>Herausforderung w\u00e4hrend der Corona-Pandemie eher in der Logistik<\/strong> der bef\u00fcllten Fl\u00e4schchen.<\/p>\n<h2>Weltweiter Bedarf an Pharmaglas kann gedeckt werden<\/h2>\n<p>Bereits im Sommer hatten<strong> die f\u00fchrenden Pharmaverpackungshersteller Schott, Gerresheimer und Stevanato Group<\/strong> eine gemeinsame Erkl\u00e4rung zur Bereitstellung von Verpackungen f\u00fcr Corona-Impfstoffe abgegeben. Jedes der drei Unternehmen stellt j\u00e4hrlich Milliarden von Fl\u00e4schchen aus sogenanntem Borosilicatglas Typ 1 her. Dieser Glastyp ist der Quasistandard in der Pharmaindustrie, wenn es um Verpackungen f\u00fcr Impfstoffe geht. Fabian St\u00f6cker: \u201eDurch die gemeinsame Erkl\u00e4rung wollten wir <strong>ein Signal an den Markt senden<\/strong> und Vertrauen in die globale pharmazeutische Versorgungskette schaffen.\u201c<\/p>\n[infotext icon]SCHOTT ist ein international f\u00fchrender Technologiekonzern auf den Gebieten Spezialglas, Glaskeramik und verwandten Hightech-Materialien. Der Spezialglashersteller stellt \u00fcber elf Milliarden Pharmaverpackungen pro Jahr her und verf\u00fcgt \u00fcber ein globales Produktionsnetzwerk mit 20 Werken und mehr als 600 Produktionslinien f\u00fcr Pharmaglas und Verpackungen. Im Gesch\u00e4ftsjahr 2019 erzielte der Konzern mit \u00fcber 16.200 Mitarbeitern einen Umsatz von 2,2 Milliarden Euro. Die <a href=\"http:\/\/www.schott.com\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">SCHOTT AG<\/a> hat ihren Hauptsitz in Mainz und befindet sich zu 100 Prozent im Besitz der Carl-Zeiss-Stiftung. Diese ist eine der \u00e4ltesten privaten und gr\u00f6\u00dften wissenschaftsf\u00f6rdernden Stiftungen in Deutschland.[\/infotext]\n","protected":false},"excerpt":{"rendered":"Before the sensitive COVID-19 vaccine arrives at the vaccination centres, it has to be produced and filled in large quantities, packaged, transported and distributed worldwide.","protected":false},"author":20,"featured_media":41828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"__cvm_playback_settings":[],"__cvm_video_id":"","rank_math_description":"Corona-Impfstoffe m\u00fcssen in gro\u00dfen Mengen produziert, in Pharmaglas abgef\u00fcllt, verpackt, transportiert und weltweit verteilt werden.","rank_math_focus_keyword":"Pharmaglas","rank_math_title":"","csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[28,22],"tags":[43,62,36,40,58902],"class_list":{"0":"post-41826","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aus-dem-magazin","8":"category-packmittel-und-packstoffe","9":"tag-aus-den-unternehmen","10":"tag-glas","11":"tag-markt","12":"tag-pharma-kosmetik-chemie","13":"tag-schott","14":"cs-entry","15":"cs-video-wrap"},"acf":[],"vimeo_video":null,"_links":{"self":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/posts\/41826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/comments?post=41826"}],"version-history":[{"count":0,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/posts\/41826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/media\/41828"}],"wp:attachment":[{"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/media?parent=41826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/categories?post=41826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/packaging-journal.de\/en\/wp-json\/wp\/v2\/tags?post=41826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}